{"id":8699,"date":"2017-10-13T09:10:40","date_gmt":"2017-10-13T09:10:40","guid":{"rendered":"http:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1.jpg"},"modified":"2017-10-13T09:10:40","modified_gmt":"2017-10-13T09:10:40","slug":"slider-realizzazioni-2-2","status":"inherit","type":"attachment","link":"https:\/\/tessituragelmi.com\/en\/slider-realizzazioni-2-2\/","title":{"rendered":"slider-realizzazioni"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-8699","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-0\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"48\" src=\"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-300x48.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-300x48.jpg 300w, https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-768x124.jpg 768w, https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-1024x165.jpg 1024w, https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1.jpg 1240w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1240,"height":200,"file":"2017\/10\/slider-realizzazioni-1.jpg","sizes":{"thumbnail":{"file":"slider-realizzazioni-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-150x150.jpg"},"medium":{"file":"slider-realizzazioni-1-300x48.jpg","width":300,"height":48,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-300x48.jpg"},"medium_large":{"file":"slider-realizzazioni-1-768x124.jpg","width":768,"height":124,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-768x124.jpg"},"large":{"file":"slider-realizzazioni-1-1024x165.jpg","width":1024,"height":165,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-1024x165.jpg"},"shop_thumbnail":{"file":"slider-realizzazioni-1-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-180x180.jpg"},"shop_catalog":{"file":"slider-realizzazioni-1-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-300x200.jpg"},"shop_single":{"file":"slider-realizzazioni-1-600x200.jpg","width":600,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-600x200.jpg"},"barrel-blog-thumb":{"file":"slider-realizzazioni-1-1170x200.jpg","width":1170,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-1170x200.jpg"},"barrel-blog-thumb-widget":{"file":"slider-realizzazioni-1-270x152.jpg","width":270,"height":152,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-270x152.jpg"},"barrel-portfolio-thumb-square":{"file":"slider-realizzazioni-1-1024x200.jpg","width":1024,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-1024x200.jpg"},"barrel-portfolio-nav":{"file":"slider-realizzazioni-1-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-100x100.jpg"},"barrel-reviews-avatar":{"file":"slider-realizzazioni-1-40x40.jpg","width":40,"height":40,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1-40x40.jpg"},"full":{"file":"slider-realizzazioni-1.jpg","width":1240,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"www.albertomerisio.it","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/tessituragelmi.com\/wp-content\/uploads\/2017\/10\/slider-realizzazioni-1.jpg","_links":{"self":[{"href":"https:\/\/tessituragelmi.com\/en\/wp-json\/wp\/v2\/media\/8699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tessituragelmi.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/tessituragelmi.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/tessituragelmi.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tessituragelmi.com\/en\/wp-json\/wp\/v2\/comments?post=8699"}]}}